{"id":664,"date":"2024-04-12T11:54:04","date_gmt":"2024-04-12T09:54:04","guid":{"rendered":"https:\/\/sarlaiguillon.fr\/?p=664"},"modified":"2024-05-15T14:56:39","modified_gmt":"2024-05-15T12:56:39","slug":"une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service","status":"publish","type":"post","link":"https:\/\/sarlaiguillon.fr\/index.php\/2024\/04\/12\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\/","title":{"rendered":"Une \u00e9quipe de professionnels proche de chez vous et \u00e0 votre service."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"664\" class=\"elementor elementor-664\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-54e9ba4 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"54e9ba4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1dd87d8\" data-id=\"1dd87d8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40415a1 elementor-widget-tablet__width-inherit elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"40415a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:1000}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tUne \u00e9quipe de professionnels proche de chez vous et \u00e0 votre service.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-205636f elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"205636f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><em>\/\/Les Rdv Parthenaisiens : M. Aiguillon, merci de nous pr\u00e9senter votre activit\u00e9 !<\/em><\/strong><\/p><p>Micka\u00ebl Aiguillon : La SARL Aiguillon que j&rsquo;ai cr\u00e9\u00e9e en 2010 est sp\u00e9cialis\u00e9e dans les travaux de terrassement, ma\u00e7onnerie et couverture. Au tout d\u00e9but, nous \u00e9tions une \u00e9quipe de 3 professionnels, install\u00e9e rue des Tisserands \u00e0 Secondigny daris les anciens locaux de l&rsquo;entreprise Niveau. Au rythme de l&rsquo;\u00e9volution de l&rsquo;entreprise, nous avons dlabord d\u00e9m\u00e9nag\u00e9 rue de la Vend\u00e9e en 2012. En 2017, un second \u00e9tablissement a \u00e9t\u00e9 cr\u00e9\u00e9 10 route de Moncoutant \u00e0 Cless\u00e9 pour y installer l&rsquo;\u00e9quipe des couvreurs. Puis, en 2022, nous avons investi dans des nouveaux locaux construits sur la zone de Bellevue \u00e0 Secondigny.<\/p><p>\u00a0<\/p><p><strong><em>\/\/Les RDV : Parlez-nous de cette nouvelle installation.<\/em><\/strong><\/p><p>M A : Ces locaux nous ont permis de b\u00e9n\u00e9ficier d&rsquo;un plus grand espace de stockage, de rangement mais aussi de cr\u00e9er un accueil plus confortable et accessible pour notre client\u00e8le. En parall\u00e8le, nous avons cr\u00e9\u00e9 une salle de r\u00e9union disponible \u00e0 la location, d\u00e9di\u00e9e aux professionnels, au milieu associatif, ainsi qu&rsquo;\u00e0 toutes les structures qui seraient \u00e0 la recherche d&rsquo;une salle pour d&rsquo;\u00e9ventuels r\u00e9unions, s\u00e9minaires, formations ou autres.<\/p><p><strong><em>\/\/Les RDV : Pouvez-vous nous en dire un peu plus sur la salle de r\u00e9union de Secondigny ?<\/em><\/strong><\/p><p>M A : C&rsquo;est un grand espace chauff\u00e9 et climatis\u00e9 de 70 m2, pour une capacit\u00e9 de 35 \u00e0 50 personnes, celle-ci est \u00e9quip\u00e9e d&rsquo;une kitchenette, d&rsquo;un parking priv\u00e9 et d&rsquo;un pr\u00e9au d&rsquo;accueil, Vous trouverez aussi \u00e0 votre disposition sur place, un vid\u00e9oprojecteur, un tableau paperboard, des tables et des chaises, ainsi qu&rsquo;une connexion wifi. De plus, nous pouvons mettre \u00e0 disposition des boissons fra\u00eeches, chaudes, des viennoiseries sur demande lors de la r\u00e9servation&#8230; C&rsquo;est une salle de travail disponible pour les professionnels, les associations&#8230; Un service tr\u00e8s appr\u00e9ci\u00e9 !<\/p><p>\u00ab <strong>Une \u00e9quipe de professionnels proches de vous et \u00e0 votre service !<\/strong> \u00bb<\/p><p><em><strong>\/\/Les RDV : Revenons \u00e0 votre activit\u00e9 et votre \u00e9quipe !<\/strong><\/em><\/p><p>M A : Nous sommes une \u00e9quipe de 15 professionnels qui se compose de la fa\u00e7on suivante : I g\u00e9rant, 2 personnes pour la partie administrative et comptable, 2 terrassiers, 7 ma\u00e7ons sur le site de Secondigny et 3 couvreurs sur le site de Cless\u00e9. Nous intervenons dans un rayon situ\u00e9 \u00e0 environ 30 kilom\u00e8tres autour de Secondigny et de Cless\u00e9. Nous collaborons avec un r\u00e9seau de professionnels en qui nous avons enti\u00e8re confiance : ma\u00eetre d&rsquo;\u0153uvre, architectes et artisans (menuisiers, carreleurs, \u00e9lectriciens, plombiers chauffagistes, charpentiers ).<\/p><p><strong><em>\/\/ Les RDV : Quels types de travaux r\u00e9alisez-vous ? <\/em><\/strong><\/p><p>M A : Concernant l&rsquo;activit\u00e9 de terrassement, nous pr\u00e9parons nos plateformes de maison et leurs fondations. Nous r\u00e9alisons \u00e9galement cette activit\u00e9 pour les b\u00e2timents agricoles et industriels. Nous intervenons sur l&rsquo;assainissement autonome et collectif, ainsi que l&rsquo;am\u00e9nagement ext\u00e9rieur des maisons et b\u00e2timents (terrasses, cl\u00f4tures, grillages&#8230;). L&rsquo;entreprise poss\u00e8de tout son mat\u00e9riel n\u00e9cessaire \u00e0 l&rsquo;\u00e9laboration de ses chantiers : pelle, t\u00e9lescopique, camion et poids lourds&#8230; Nous sommes donc au service des particuliers mais aussi des professionnels (cr\u00e9ation ou modification de b\u00e2timents industriels). Du c\u00f4t\u00e9 de la ma\u00e7onnerie, couverture et la zinguerie, nous intervenons aussi bien pour du neuf que pour de la r\u00e9novation, avec \u00e9galement un service de d\u00e9pannage.<\/p><p><strong><em>\/\/Les RDV : Qu&rsquo;entendez-vous par la notion de service etde d\u00e9pannage ? <\/em><\/strong><\/p><p>M A : Il est important pour nous d&rsquo;apporter un service aux personnes pr\u00e9sentes sur notre territoire, ainsi que pour notre client\u00e8le, Comme lors d&rsquo;un \u00e9v\u00e9nement climatique, par exemple, qui peut provoquer des d\u00e9g\u00e2ts, nous mesurons parfaitement l&rsquo;urgence de la situation et nous mettons tout en \u0153uvre pour intervenir dans les plus brefs d\u00e9lais. La notion de service se situe \u00e9galement dans notre capacit\u00e9 \u00e0 mettre en relation notre r\u00e9seau de professionnels pour la r\u00e9alisation d&rsquo;un futur projet de maison, de r\u00e9novation ou d&rsquo;agrandissement. Il faut \u00eatre s\u00fbr de faire appel \u00e0 des artisans qui connaissent leur m\u00e9tier, les savoir-faire locaux ainsi que les normes en vigueur.<\/p><p><strong><em>\/\/Les RDV : Et pour conclure ? <\/em><\/strong><\/p><p>M A : Besoin de terrassiers ma\u00e7ons ou couvreurs pour votre projet de cr\u00e9ation, r\u00e9novation ou agrandissement, que vous soyez un particulier ou un professionnel, nous serons ravis de tout mettre en \u0153uvre pour vous satisfaire et pour vous faire b\u00e9n\u00e9ficier de notre exp\u00e9rience et expertise ! Contactez-nous, nous serons ravis d&rsquo;\u00e9changer autour de vos projets. Alors \u00e0 tr\u00e8s bient\u00f4t !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-586a267 elementor-invisible elementor-widget elementor-widget-eael-creative-button\" data-id=\"586a267\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:2000}\" data-widget_type=\"eael-creative-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"eael-creative-button-wrapper\">\n\n            <a class=\"eael-creative-button eael-creative-button--rayen eael-cb-icon-position-\" href=\"https:\/\/www.poitoucharentes.cerfrance.fr\/up\/SI\/WEB\/SARLAIGUILLON-locationsalle\/articlerdvparthenaisiens.jpg\" data-text=\"D\u00e9couvrez l&#039;article des RDV Parthenaisiens\">\n            \t    \n                <div class=\"creative-button-inner\">\n\n                    \n                    <span class=\"cretive-button-text\">D\u00e9couvrez l'article des RDV Parthenaisiens<\/span>\n\n                                    <\/div>\n\t                        <\/a>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\/\/Les Rdv Parthenaisiens : M. Aiguillon, merci de nous pr\u00e9senter votre activit\u00e9 ! Micka\u00ebl Aiguillon : La SARL Aiguillon que j&rsquo;ai cr\u00e9\u00e9e en 2010 est sp\u00e9cialis\u00e9e dans les travaux de&hellip;<\/p>\n","protected":false},"author":6,"featured_media":665,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"status","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-664","post","type-post","status-publish","format-status","has-post-thumbnail","hentry","category-non-classe","post_format-post-format-status"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Une \u00e9quipe de professionnels proche de chez vous et \u00e0 votre service. \/\/Les Rdv Parthenaisiens : M. Aiguillon, merci de nous pr\u00e9senter votre activit\u00e9 !Micka\u00ebl Aiguillon : La SARL Aiguillon que j\u2019ai cr\u00e9\u00e9e en 2010 est sp\u00e9cialis\u00e9e dans les travaux de terrassement, ma\u00e7onnerie et couverture. Au tout d\u00e9but, nous \u00e9tions une \u00e9quipe de 3 professionnels,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"C3454ANC3\"\/>\n\t<meta name=\"google-site-verification\" content=\"0pUCZNIghWd_t4Newj74Gjd3wJJ58qr_lIcXsKloxm8\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/sarlaiguillon.fr\/index.php\/2024\/04\/12\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"SARL AIGUILLON -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Une \u00e9quipe de professionnels proche de chez vous et \u00e0 votre service. - SARL AIGUILLON\" \/>\n\t\t<meta property=\"og:description\" content=\"Une \u00e9quipe de professionnels proche de chez vous et \u00e0 votre service. \/\/Les Rdv Parthenaisiens : M. Aiguillon, merci de nous pr\u00e9senter votre activit\u00e9 !Micka\u00ebl Aiguillon : La SARL Aiguillon que j\u2019ai cr\u00e9\u00e9e en 2010 est sp\u00e9cialis\u00e9e dans les travaux de terrassement, ma\u00e7onnerie et couverture. Au tout d\u00e9but, nous \u00e9tions une \u00e9quipe de 3 professionnels,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/sarlaiguillon.fr\/index.php\/2024\/04\/12\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/sarlaiguillon.fr\/wp-content\/uploads\/2022\/10\/cropped-2022-10-17_14h22_44.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/sarlaiguillon.fr\/wp-content\/uploads\/2022\/10\/cropped-2022-10-17_14h22_44.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-04-12T09:54:04+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-05-15T12:56:39+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Une \u00e9quipe de professionnels proche de chez vous et \u00e0 votre service. - SARL AIGUILLON\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Une \u00e9quipe de professionnels proche de chez vous et \u00e0 votre service. \/\/Les Rdv Parthenaisiens : M. Aiguillon, merci de nous pr\u00e9senter votre activit\u00e9 !Micka\u00ebl Aiguillon : La SARL Aiguillon que j\u2019ai cr\u00e9\u00e9e en 2010 est sp\u00e9cialis\u00e9e dans les travaux de terrassement, ma\u00e7onnerie et couverture. Au tout d\u00e9but, nous \u00e9tions une \u00e9quipe de 3 professionnels,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/sarlaiguillon.fr\/wp-content\/uploads\/2022\/10\/cropped-2022-10-17_14h22_44.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/sarlaiguillon.fr\\\/index.php\\\/2024\\\/04\\\/12\\\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\\\/#blogposting\",\"name\":\"Une \\u00e9quipe de professionnels proche de chez vous et \\u00e0 votre service. - SARL AIGUILLON\",\"headline\":\"Une \\u00e9quipe de professionnels proche de chez vous et \\u00e0 votre service.\",\"author\":{\"@id\":\"https:\\\/\\\/sarlaiguillon.fr\\\/index.php\\\/author\\\/c3454anc3\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/sarlaiguillon.fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/sarlaiguillon.fr\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/1.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Vue a\\u00e9rienne de l\\u2019entrep\\u00f4t de la SARL Aiguillon, \\u00e9quip\\u00e9 de mat\\u00e9riel professionnel pour la ma\\u00e7onnerie et la construction : pelle, tractopelle et camion\"},\"datePublished\":\"2024-04-12T11:54:04+02:00\",\"dateModified\":\"2024-05-15T14:56:39+02:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sarlaiguillon.fr\\\/index.php\\\/2024\\\/04\\\/12\\\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/sarlaiguillon.fr\\\/index.php\\\/2024\\\/04\\\/12\\\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\\\/#webpage\"},\"articleSection\":\"Non class\\u00e9, \\u00c9tat\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sarlaiguillon.fr\\\/index.php\\\/2024\\\/04\\\/12\\\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sarlaiguillon.fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sarlaiguillon.fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sarlaiguillon.fr\\\/index.php\\\/category\\\/non-classe\\\/#listItem\",\"name\":\"Non class\\u00e9\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sarlaiguillon.fr\\\/index.php\\\/category\\\/non-classe\\\/#listItem\",\"position\":2,\"name\":\"Non class\\u00e9\",\"item\":\"https:\\\/\\\/sarlaiguillon.fr\\\/index.php\\\/category\\\/non-classe\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sarlaiguillon.fr\\\/index.php\\\/2024\\\/04\\\/12\\\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\\\/#listItem\",\"name\":\"Une \\u00e9quipe de professionnels proche de chez vous et \\u00e0 votre service.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sarlaiguillon.fr#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sarlaiguillon.fr\\\/index.php\\\/2024\\\/04\\\/12\\\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\\\/#listItem\",\"position\":3,\"name\":\"Une \\u00e9quipe de professionnels proche de chez vous et \\u00e0 votre service.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sarlaiguillon.fr\\\/index.php\\\/category\\\/non-classe\\\/#listItem\",\"name\":\"Non class\\u00e9\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sarlaiguillon.fr\\\/#organization\",\"name\":\"SARL AIGUILLON\",\"url\":\"https:\\\/\\\/sarlaiguillon.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/sarlaiguillon.fr\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/cropped-2022-10-17_14h22_44.png\",\"@id\":\"https:\\\/\\\/sarlaiguillon.fr\\\/index.php\\\/2024\\\/04\\\/12\\\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\\\/#organizationLogo\",\"width\":997,\"height\":225,\"caption\":\"Logo de la SARL Aiguillon, illustrant notre expertise en ma\\u00e7onnerie, fondations et construction de maisons.\"},\"image\":{\"@id\":\"https:\\\/\\\/sarlaiguillon.fr\\\/index.php\\\/2024\\\/04\\\/12\\\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sarlaiguillon.fr\\\/index.php\\\/author\\\/c3454anc3\\\/#author\",\"url\":\"https:\\\/\\\/sarlaiguillon.fr\\\/index.php\\\/author\\\/c3454anc3\\\/\",\"name\":\"C3454ANC3\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/689d73f8b40e42592fdf413daea2e9ab86b475c1d45fc6d19415df735db735c7?s=96&d=mm&r=g\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sarlaiguillon.fr\\\/index.php\\\/2024\\\/04\\\/12\\\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\\\/#webpage\",\"url\":\"https:\\\/\\\/sarlaiguillon.fr\\\/index.php\\\/2024\\\/04\\\/12\\\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\\\/\",\"name\":\"Une \\u00e9quipe de professionnels proche de chez vous et \\u00e0 votre service. - SARL AIGUILLON\",\"description\":\"Une \\u00e9quipe de professionnels proche de chez vous et \\u00e0 votre service. \\\/\\\/Les Rdv Parthenaisiens : M. Aiguillon, merci de nous pr\\u00e9senter votre activit\\u00e9 !Micka\\u00ebl Aiguillon : La SARL Aiguillon que j\\u2019ai cr\\u00e9\\u00e9e en 2010 est sp\\u00e9cialis\\u00e9e dans les travaux de terrassement, ma\\u00e7onnerie et couverture. Au tout d\\u00e9but, nous \\u00e9tions une \\u00e9quipe de 3 professionnels,\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sarlaiguillon.fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sarlaiguillon.fr\\\/index.php\\\/2024\\\/04\\\/12\\\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/sarlaiguillon.fr\\\/index.php\\\/author\\\/c3454anc3\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/sarlaiguillon.fr\\\/index.php\\\/author\\\/c3454anc3\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/sarlaiguillon.fr\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/1.jpg\",\"@id\":\"https:\\\/\\\/sarlaiguillon.fr\\\/index.php\\\/2024\\\/04\\\/12\\\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\\\/#mainImage\",\"width\":1280,\"height\":720,\"caption\":\"Vue a\\u00e9rienne de l\\u2019entrep\\u00f4t de la SARL Aiguillon, \\u00e9quip\\u00e9 de mat\\u00e9riel professionnel pour la ma\\u00e7onnerie et la construction : pelle, tractopelle et camion\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sarlaiguillon.fr\\\/index.php\\\/2024\\\/04\\\/12\\\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\\\/#mainImage\"},\"datePublished\":\"2024-04-12T11:54:04+02:00\",\"dateModified\":\"2024-05-15T14:56:39+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sarlaiguillon.fr\\\/#website\",\"url\":\"https:\\\/\\\/sarlaiguillon.fr\\\/\",\"name\":\"SARL AIGUILLON\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/sarlaiguillon.fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Une \u00e9quipe de professionnels proche de chez vous et \u00e0 votre service. - SARL AIGUILLON<\/title>\n\n","aioseo_head_json":{"title":"Une \u00e9quipe de professionnels proche de chez vous et \u00e0 votre service. - SARL AIGUILLON","description":"Une \u00e9quipe de professionnels proche de chez vous et \u00e0 votre service. \/\/Les Rdv Parthenaisiens : M. Aiguillon, merci de nous pr\u00e9senter votre activit\u00e9 !Micka\u00ebl Aiguillon : La SARL Aiguillon que j\u2019ai cr\u00e9\u00e9e en 2010 est sp\u00e9cialis\u00e9e dans les travaux de terrassement, ma\u00e7onnerie et couverture. Au tout d\u00e9but, nous \u00e9tions une \u00e9quipe de 3 professionnels,","canonical_url":"https:\/\/sarlaiguillon.fr\/index.php\/2024\/04\/12\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"0pUCZNIghWd_t4Newj74Gjd3wJJ58qr_lIcXsKloxm8","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/sarlaiguillon.fr\/index.php\/2024\/04\/12\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\/#blogposting","name":"Une \u00e9quipe de professionnels proche de chez vous et \u00e0 votre service. - SARL AIGUILLON","headline":"Une \u00e9quipe de professionnels proche de chez vous et \u00e0 votre service.","author":{"@id":"https:\/\/sarlaiguillon.fr\/index.php\/author\/c3454anc3\/#author"},"publisher":{"@id":"https:\/\/sarlaiguillon.fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/sarlaiguillon.fr\/wp-content\/uploads\/2024\/04\/1.jpg","width":1280,"height":720,"caption":"Vue a\u00e9rienne de l\u2019entrep\u00f4t de la SARL Aiguillon, \u00e9quip\u00e9 de mat\u00e9riel professionnel pour la ma\u00e7onnerie et la construction : pelle, tractopelle et camion"},"datePublished":"2024-04-12T11:54:04+02:00","dateModified":"2024-05-15T14:56:39+02:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/sarlaiguillon.fr\/index.php\/2024\/04\/12\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\/#webpage"},"isPartOf":{"@id":"https:\/\/sarlaiguillon.fr\/index.php\/2024\/04\/12\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\/#webpage"},"articleSection":"Non class\u00e9, \u00c9tat"},{"@type":"BreadcrumbList","@id":"https:\/\/sarlaiguillon.fr\/index.php\/2024\/04\/12\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/sarlaiguillon.fr#listItem","position":1,"name":"Home","item":"https:\/\/sarlaiguillon.fr","nextItem":{"@type":"ListItem","@id":"https:\/\/sarlaiguillon.fr\/index.php\/category\/non-classe\/#listItem","name":"Non class\u00e9"}},{"@type":"ListItem","@id":"https:\/\/sarlaiguillon.fr\/index.php\/category\/non-classe\/#listItem","position":2,"name":"Non class\u00e9","item":"https:\/\/sarlaiguillon.fr\/index.php\/category\/non-classe\/","nextItem":{"@type":"ListItem","@id":"https:\/\/sarlaiguillon.fr\/index.php\/2024\/04\/12\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\/#listItem","name":"Une \u00e9quipe de professionnels proche de chez vous et \u00e0 votre service."},"previousItem":{"@type":"ListItem","@id":"https:\/\/sarlaiguillon.fr#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/sarlaiguillon.fr\/index.php\/2024\/04\/12\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\/#listItem","position":3,"name":"Une \u00e9quipe de professionnels proche de chez vous et \u00e0 votre service.","previousItem":{"@type":"ListItem","@id":"https:\/\/sarlaiguillon.fr\/index.php\/category\/non-classe\/#listItem","name":"Non class\u00e9"}}]},{"@type":"Organization","@id":"https:\/\/sarlaiguillon.fr\/#organization","name":"SARL AIGUILLON","url":"https:\/\/sarlaiguillon.fr\/","logo":{"@type":"ImageObject","url":"https:\/\/sarlaiguillon.fr\/wp-content\/uploads\/2022\/10\/cropped-2022-10-17_14h22_44.png","@id":"https:\/\/sarlaiguillon.fr\/index.php\/2024\/04\/12\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\/#organizationLogo","width":997,"height":225,"caption":"Logo de la SARL Aiguillon, illustrant notre expertise en ma\u00e7onnerie, fondations et construction de maisons."},"image":{"@id":"https:\/\/sarlaiguillon.fr\/index.php\/2024\/04\/12\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/sarlaiguillon.fr\/index.php\/author\/c3454anc3\/#author","url":"https:\/\/sarlaiguillon.fr\/index.php\/author\/c3454anc3\/","name":"C3454ANC3","image":{"@type":"ImageObject","url":"https:\/\/secure.gravatar.com\/avatar\/689d73f8b40e42592fdf413daea2e9ab86b475c1d45fc6d19415df735db735c7?s=96&d=mm&r=g"}},{"@type":"WebPage","@id":"https:\/\/sarlaiguillon.fr\/index.php\/2024\/04\/12\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\/#webpage","url":"https:\/\/sarlaiguillon.fr\/index.php\/2024\/04\/12\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\/","name":"Une \u00e9quipe de professionnels proche de chez vous et \u00e0 votre service. - SARL AIGUILLON","description":"Une \u00e9quipe de professionnels proche de chez vous et \u00e0 votre service. \/\/Les Rdv Parthenaisiens : M. Aiguillon, merci de nous pr\u00e9senter votre activit\u00e9 !Micka\u00ebl Aiguillon : La SARL Aiguillon que j\u2019ai cr\u00e9\u00e9e en 2010 est sp\u00e9cialis\u00e9e dans les travaux de terrassement, ma\u00e7onnerie et couverture. Au tout d\u00e9but, nous \u00e9tions une \u00e9quipe de 3 professionnels,","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/sarlaiguillon.fr\/#website"},"breadcrumb":{"@id":"https:\/\/sarlaiguillon.fr\/index.php\/2024\/04\/12\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\/#breadcrumblist"},"author":{"@id":"https:\/\/sarlaiguillon.fr\/index.php\/author\/c3454anc3\/#author"},"creator":{"@id":"https:\/\/sarlaiguillon.fr\/index.php\/author\/c3454anc3\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/sarlaiguillon.fr\/wp-content\/uploads\/2024\/04\/1.jpg","@id":"https:\/\/sarlaiguillon.fr\/index.php\/2024\/04\/12\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\/#mainImage","width":1280,"height":720,"caption":"Vue a\u00e9rienne de l\u2019entrep\u00f4t de la SARL Aiguillon, \u00e9quip\u00e9 de mat\u00e9riel professionnel pour la ma\u00e7onnerie et la construction : pelle, tractopelle et camion"},"primaryImageOfPage":{"@id":"https:\/\/sarlaiguillon.fr\/index.php\/2024\/04\/12\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\/#mainImage"},"datePublished":"2024-04-12T11:54:04+02:00","dateModified":"2024-05-15T14:56:39+02:00"},{"@type":"WebSite","@id":"https:\/\/sarlaiguillon.fr\/#website","url":"https:\/\/sarlaiguillon.fr\/","name":"SARL AIGUILLON","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/sarlaiguillon.fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"SARL AIGUILLON -","og:type":"article","og:title":"Une \u00e9quipe de professionnels proche de chez vous et \u00e0 votre service. - SARL AIGUILLON","og:description":"Une \u00e9quipe de professionnels proche de chez vous et \u00e0 votre service. \/\/Les Rdv Parthenaisiens : M. Aiguillon, merci de nous pr\u00e9senter votre activit\u00e9 !Micka\u00ebl Aiguillon : La SARL Aiguillon que j\u2019ai cr\u00e9\u00e9e en 2010 est sp\u00e9cialis\u00e9e dans les travaux de terrassement, ma\u00e7onnerie et couverture. Au tout d\u00e9but, nous \u00e9tions une \u00e9quipe de 3 professionnels,","og:url":"https:\/\/sarlaiguillon.fr\/index.php\/2024\/04\/12\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\/","og:image":"https:\/\/sarlaiguillon.fr\/wp-content\/uploads\/2022\/10\/cropped-2022-10-17_14h22_44.png","og:image:secure_url":"https:\/\/sarlaiguillon.fr\/wp-content\/uploads\/2022\/10\/cropped-2022-10-17_14h22_44.png","article:published_time":"2024-04-12T09:54:04+00:00","article:modified_time":"2024-05-15T12:56:39+00:00","twitter:card":"summary_large_image","twitter:title":"Une \u00e9quipe de professionnels proche de chez vous et \u00e0 votre service. - SARL AIGUILLON","twitter:description":"Une \u00e9quipe de professionnels proche de chez vous et \u00e0 votre service. \/\/Les Rdv Parthenaisiens : M. Aiguillon, merci de nous pr\u00e9senter votre activit\u00e9 !Micka\u00ebl Aiguillon : La SARL Aiguillon que j\u2019ai cr\u00e9\u00e9e en 2010 est sp\u00e9cialis\u00e9e dans les travaux de terrassement, ma\u00e7onnerie et couverture. Au tout d\u00e9but, nous \u00e9tions une \u00e9quipe de 3 professionnels,","twitter:image":"https:\/\/sarlaiguillon.fr\/wp-content\/uploads\/2022\/10\/cropped-2022-10-17_14h22_44.png"},"aioseo_meta_data":{"post_id":"664","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-05-13 02:45:01","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2024-04-12 09:54:05","updated":"2026-05-13 02:45:01"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/sarlaiguillon.fr\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/sarlaiguillon.fr\/index.php\/category\/non-classe\/\" title=\"Non class\u00e9\">Non class\u00e9<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tUne \u00e9quipe de professionnels proche de chez vous et \u00e0 votre service.\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/sarlaiguillon.fr"},{"label":"Non class\u00e9","link":"https:\/\/sarlaiguillon.fr\/index.php\/category\/non-classe\/"},{"label":"Une \u00e9quipe de professionnels proche de chez vous et \u00e0 votre service.","link":"https:\/\/sarlaiguillon.fr\/index.php\/2024\/04\/12\/une-equipe-de-professionnels-proche-de-chez-vous-et-a-votre-service\/"}],"_links":{"self":[{"href":"https:\/\/sarlaiguillon.fr\/index.php\/wp-json\/wp\/v2\/posts\/664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sarlaiguillon.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sarlaiguillon.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sarlaiguillon.fr\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sarlaiguillon.fr\/index.php\/wp-json\/wp\/v2\/comments?post=664"}],"version-history":[{"count":8,"href":"https:\/\/sarlaiguillon.fr\/index.php\/wp-json\/wp\/v2\/posts\/664\/revisions"}],"predecessor-version":[{"id":695,"href":"https:\/\/sarlaiguillon.fr\/index.php\/wp-json\/wp\/v2\/posts\/664\/revisions\/695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sarlaiguillon.fr\/index.php\/wp-json\/wp\/v2\/media\/665"}],"wp:attachment":[{"href":"https:\/\/sarlaiguillon.fr\/index.php\/wp-json\/wp\/v2\/media?parent=664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sarlaiguillon.fr\/index.php\/wp-json\/wp\/v2\/categories?post=664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sarlaiguillon.fr\/index.php\/wp-json\/wp\/v2\/tags?post=664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}